{"id":57,"date":"2010-12-21T18:48:05","date_gmt":"2010-12-21T20:48:05","guid":{"rendered":"http:\/\/www.encontrasantos.com.br\/noticias\/?p=57"},"modified":"2019-04-29T18:05:16","modified_gmt":"2019-04-29T21:05:16","slug":"orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos","status":"publish","type":"post","link":"https:\/\/www.encontrasantos.com.br\/sobre\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\/","title":{"rendered":"Orla de Santos recebe refor\u00e7o de 185 guardi\u00f5es-cidad\u00e3os"},"content":{"rendered":"<div class=\"79600775c85722932cbf26dff21860fb\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Cerca de 185 guardi\u00f5es-cidad\u00e3os come\u00e7am a atuar na orla de Santos a partir desta quarta-feira at\u00e9 o dia 31 de janeiro. O objetivo \u00e9 orientar moradores e turistas e evitar conflitos durante a temporada de ver\u00e3o.<\/p>\n<p>O efetivo atuar\u00e1 da divisa com S\u00e3o Vicente at\u00e9 o ferry-boat, 24 horas por dia, todos os dias da semana.<\/p>\n<p>Os guardi\u00f5es-cidad\u00e3os foram treinados para alertar a popula\u00e7\u00e3o sobre hor\u00e1rios e locais adequados para a pr\u00e1tica de esportes (bicicletas, skate, pipas e frescobol, entre outros), como proceder no caso de crian\u00e7as perdidas e tamb\u00e9m informar sobre a quest\u00e3o do uso de som alto em ve\u00edculos estacionados.<\/p>\n<p>No caso de crian\u00e7as perdidas, o guardi\u00e3o-cidad\u00e3o ir\u00e1 encaminh\u00e1-la at\u00e9 o Posto de Salvamento mais pr\u00f3ximo, onde ficar\u00e1 por uma hora. Depois, ser\u00e1 encaminhada para o &#8216;Arena e Cia&#8217;, ao lado do Canal 3, onde ficar\u00e1 a base de apoio da Guarda Municipal.<\/p>\n<p><strong>Ver\u00e3o com Seguran\u00e7a<br \/>\n<\/strong><br \/>\nNa pr\u00f3xima segunda-feira entra em vigor a Opera\u00e7\u00e3o Ver\u00e3o com Seguran\u00e7a. A opera\u00e7\u00e3o ter\u00e1 refor\u00e7o de 10 investigadores\/escriv\u00e3es e de 200 policiais militares (80 pra\u00e7as e 120 cadetes da Academia do Barro Branco). A Secretaria de Seguran\u00e7a (Seseg) manter\u00e1, durante 24 horas, efetivo de 100 guardas municipais na orla.<\/p>\n<p>Para auxiliar na opera\u00e7\u00e3o tamb\u00e9m haver\u00e1 o apoio de oito quadriciclos (Guarda Municipal e PM) na faixa da areia; uma viatura da PM por canal na conflu\u00eancia com a praia (sete ao todo); oito bicicletas (sendo duas el\u00e9tricas) e seis motos da GM; al\u00e9m do SIM (Sistema Informatizado de Monitoramento) da prefeitura, que conta com 20 c\u00e2meras na orla, cinco no Centro Hist\u00f3rico e tr\u00eas na Alemoa.<\/p>\n<p>O esquema inclui ainda helic\u00f3ptero \u00c1guia da PM e 15 integrantes do Programa Salva Surf, que ir\u00e3o auxiliar os bombeiros.<\/p>\n<p><em>Fonte: A Tribuna<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Cerca de 185 guardi\u00f5es-cidad\u00e3os come\u00e7am a atuar na orla de Santos a partir desta quarta-feira at\u00e9 o dia 31 de janeiro. O objetivo \u00e9 orientar moradores e turistas e evitar conflitos durante a temporada de ver\u00e3o. O efetivo atuar\u00e1 da divisa com S\u00e3o Vicente at\u00e9 o ferry-boat, 24 horas por dia, todos os dias da semana. Os guardi\u00f5es-cidad\u00e3os foram treinados para alertar a popula\u00e7\u00e3o sobre hor\u00e1rios e locais adequados para a pr\u00e1tica de esportes (bicicletas, skate, pipas e frescobol, entre outros), como proceder no caso de crian\u00e7as perdidas e tamb\u00e9m informar sobre a quest\u00e3o do uso de som alto em <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[14],"class_list":["post-57","post","type-post","status-publish","format-standard","hentry","category-noticias-em-santos","tag-santos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Orla de Santos recebe refor\u00e7o de 185 guardi\u00f5es-cidad\u00e3os - Encontra Santos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encontrasantos.com.br\/sobre\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orla de Santos recebe refor\u00e7o de 185 guardi\u00f5es-cidad\u00e3os - Encontra Santos\" \/>\n<meta property=\"og:description\" content=\"Cerca de 185 guardi\u00f5es-cidad\u00e3os come\u00e7am a atuar na orla de Santos a partir desta quarta-feira at\u00e9 o dia 31 de janeiro. O objetivo \u00e9 orientar moradores e turistas e evitar conflitos durante a temporada de ver\u00e3o. O efetivo atuar\u00e1 da divisa com S\u00e3o Vicente at\u00e9 o ferry-boat, 24 horas por dia, todos os dias da semana. Os guardi\u00f5es-cidad\u00e3os foram treinados para alertar a popula\u00e7\u00e3o sobre hor\u00e1rios e locais adequados para a pr\u00e1tica de esportes (bicicletas, skate, pipas e frescobol, entre outros), como proceder no caso de crian\u00e7as perdidas e tamb\u00e9m informar sobre a quest\u00e3o do uso de som alto em\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encontrasantos.com.br\/sobre\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontra Santos\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-21T20:48:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-29T21:05:16+00:00\" \/>\n<meta name=\"author\" content=\"Encontra Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Encontra Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\\\/\"},\"author\":{\"name\":\"Encontra Santos\",\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/c048a1af2d003b660d350a57d8081717\"},\"headline\":\"Orla de Santos recebe refor\u00e7o de 185 guardi\u00f5es-cidad\u00e3os\",\"datePublished\":\"2010-12-21T20:48:05+00:00\",\"dateModified\":\"2019-04-29T21:05:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\\\/\"},\"wordCount\":325,\"commentCount\":0,\"keywords\":[\"Santos\"],\"articleSection\":[\"Not\u00edcias Santos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\\\/\",\"url\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\\\/\",\"name\":\"Orla de Santos recebe refor\u00e7o de 185 guardi\u00f5es-cidad\u00e3os - Encontra Santos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/#website\"},\"datePublished\":\"2010-12-21T20:48:05+00:00\",\"dateModified\":\"2019-04-29T21:05:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/c048a1af2d003b660d350a57d8081717\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Orla de Santos recebe refor\u00e7o de 185 guardi\u00f5es-cidad\u00e3os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/\",\"name\":\"Encontra Santos\",\"description\":\"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Santos e regi\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/c048a1af2d003b660d350a57d8081717\",\"name\":\"Encontra Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"caption\":\"Encontra Santos\"},\"sameAs\":[\"http:\\\/\\\/www.encontrasantos.com.br\"],\"url\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/author\\\/esantos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orla de Santos recebe refor\u00e7o de 185 guardi\u00f5es-cidad\u00e3os - Encontra Santos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encontrasantos.com.br\/sobre\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\/","og_locale":"pt_BR","og_type":"article","og_title":"Orla de Santos recebe refor\u00e7o de 185 guardi\u00f5es-cidad\u00e3os - Encontra Santos","og_description":"Cerca de 185 guardi\u00f5es-cidad\u00e3os come\u00e7am a atuar na orla de Santos a partir desta quarta-feira at\u00e9 o dia 31 de janeiro. O objetivo \u00e9 orientar moradores e turistas e evitar conflitos durante a temporada de ver\u00e3o. O efetivo atuar\u00e1 da divisa com S\u00e3o Vicente at\u00e9 o ferry-boat, 24 horas por dia, todos os dias da semana. Os guardi\u00f5es-cidad\u00e3os foram treinados para alertar a popula\u00e7\u00e3o sobre hor\u00e1rios e locais adequados para a pr\u00e1tica de esportes (bicicletas, skate, pipas e frescobol, entre outros), como proceder no caso de crian\u00e7as perdidas e tamb\u00e9m informar sobre a quest\u00e3o do uso de som alto em","og_url":"https:\/\/www.encontrasantos.com.br\/sobre\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\/","og_site_name":"Encontra Santos","article_published_time":"2010-12-21T20:48:05+00:00","article_modified_time":"2019-04-29T21:05:16+00:00","author":"Encontra Santos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Encontra Santos","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontrasantos.com.br\/sobre\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\/#article","isPartOf":{"@id":"https:\/\/www.encontrasantos.com.br\/sobre\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\/"},"author":{"name":"Encontra Santos","@id":"https:\/\/www.encontrasantos.com.br\/sobre\/#\/schema\/person\/c048a1af2d003b660d350a57d8081717"},"headline":"Orla de Santos recebe refor\u00e7o de 185 guardi\u00f5es-cidad\u00e3os","datePublished":"2010-12-21T20:48:05+00:00","dateModified":"2019-04-29T21:05:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.encontrasantos.com.br\/sobre\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\/"},"wordCount":325,"commentCount":0,"keywords":["Santos"],"articleSection":["Not\u00edcias Santos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.encontrasantos.com.br\/sobre\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.encontrasantos.com.br\/sobre\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\/","url":"https:\/\/www.encontrasantos.com.br\/sobre\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\/","name":"Orla de Santos recebe refor\u00e7o de 185 guardi\u00f5es-cidad\u00e3os - Encontra Santos","isPartOf":{"@id":"https:\/\/www.encontrasantos.com.br\/sobre\/#website"},"datePublished":"2010-12-21T20:48:05+00:00","dateModified":"2019-04-29T21:05:16+00:00","author":{"@id":"https:\/\/www.encontrasantos.com.br\/sobre\/#\/schema\/person\/c048a1af2d003b660d350a57d8081717"},"breadcrumb":{"@id":"https:\/\/www.encontrasantos.com.br\/sobre\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.encontrasantos.com.br\/sobre\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontrasantos.com.br\/sobre\/orla-de-santos-recebe-reforco-de-185-guardioes-cidadaos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontrasantos.com.br\/sobre\/"},{"@type":"ListItem","position":2,"name":"Orla de Santos recebe refor\u00e7o de 185 guardi\u00f5es-cidad\u00e3os"}]},{"@type":"WebSite","@id":"https:\/\/www.encontrasantos.com.br\/sobre\/#website","url":"https:\/\/www.encontrasantos.com.br\/sobre\/","name":"Encontra Santos","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Santos e regi\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encontrasantos.com.br\/sobre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.encontrasantos.com.br\/sobre\/#\/schema\/person\/c048a1af2d003b660d350a57d8081717","name":"Encontra Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","caption":"Encontra Santos"},"sameAs":["http:\/\/www.encontrasantos.com.br"],"url":"https:\/\/www.encontrasantos.com.br\/sobre\/author\/esantos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/posts\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=57"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/posts\/57\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=57"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=57"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}