{"id":5006,"date":"2026-02-03T12:56:08","date_gmt":"2026-02-03T15:56:08","guid":{"rendered":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/"},"modified":"2026-02-03T12:56:08","modified_gmt":"2026-02-03T15:56:08","slug":"curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12","status":"publish","type":"post","link":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/","title":{"rendered":"Curso para motorista profissional de Santos inscreve at\u00e9 o dia 12"},"content":{"rendered":"<div class=\"79600775c85722932cbf26dff21860fb\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<h2>O que \u00e9 o curso para motorista profissional?<\/h2>\n<p>O curso voltado para motoristas profissionais tem como principal prop\u00f3sito capacitar os cidad\u00e3os de Santos para atuar como taxistas, condutores de transporte escolar ou de autolota\u00e7\u00e3o. Essa forma\u00e7\u00e3o ajuda a garantir que os motoristas estejam bem preparados para exercer suas fun\u00e7\u00f5es, promovendo a seguran\u00e7a no tr\u00e2nsito e o cumprimento das normas vigentes.<\/p>\n<h2>Quem pode se inscrever no curso?<\/h2>\n<p>S\u00e3o eleg\u00edveis para participar do curso todos os residentes da cidade de Santos, desde que atendam aos crit\u00e9rios estabelecidos. A forma\u00e7\u00e3o foi desenvolvida para aqueles que desejam entrar no mercado de trabalho na \u00e1rea de transporte ou que simplesmente queiram atualizar seus conhecimentos.<\/p>\n<h2>Como fazer a inscri\u00e7\u00e3o<\/h2>\n<p>Os interessados podem realizar a inscri\u00e7\u00e3o atrav\u00e9s do portal Santos Digital. \u00c9 fundamental acessar a se\u00e7\u00e3o &#8220;Tr\u00e2nsito e mobilidade urbana&#8221;, seguir para &#8220;Educa\u00e7\u00e3o para o tr\u00e2nsito&#8221; e escolher a op\u00e7\u00e3o correspondente ao &#8220;Curso de aperfei\u00e7oamento profissional para motorista&#8221;. O processo \u00e9 simples e pode ser realizado de forma r\u00e1pida.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.encontrasantos.com.br\/sobre\/wp-content\/uploads\/2026\/02\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12.webp\" alt=\"curso para motorista profissional de Santos\" loading=\"lazy\" \/><\/p>\n<h2>Documentos necess\u00e1rios para a inscri\u00e7\u00e3o<\/h2>\n<p>Para efetivar a matr\u00edcula no curso, os candidatos devem apresentar alguns documentos essenciais, que incluem:<\/p>\n<ul>\n<li>C\u00f3pia leg\u00edvel da Carteira Nacional de Habilita\u00e7\u00e3o (CNH).<\/li>\n<li>Comprovante de resid\u00eancia em Santos, que deve ter sido emitido nos \u00faltimos 90 dias.<\/li>\n<\/ul>\n<p>Os documentos devem ser anexados no momento da inscri\u00e7\u00e3o, conforme as instru\u00e7\u00f5es fornecidas no portal.<\/p>\n<h2>Datas e hor\u00e1rios das aulas<\/h2>\n<p>A segunda turma do curso deste ano ter\u00e1 suas atividades realizadas de 23 de fevereiro a 3 de mar\u00e7o. As aulas acontecer\u00e3o todos os dias das 9h \u00e0s 11h30, proporcionando um hor\u00e1rio acess\u00edvel para que os candidatos possam participar sem comprometer outras atividades.<\/p>\n<h2>Conte\u00fado program\u00e1tico do curso<\/h2>\n<p>A capacita\u00e7\u00e3o \u00e9 composta por sete aulas, cada uma abordando um tema diferente e relevante para o desenvolvimento profissional dos motoristas. Os t\u00f3picos incluem:<\/p>\n<ul>\n<li>Legisla\u00e7\u00e3o Municipal<\/li>\n<li>Dire\u00e7\u00e3o Defensiva<\/li>\n<li>Legisla\u00e7\u00e3o de Tr\u00e2nsito<\/li>\n<li>No\u00e7\u00f5es de Mec\u00e2nica<\/li>\n<li>Primeiros Socorros<\/li>\n<li>Rela\u00e7\u00f5es Humanas<\/li>\n<li>Turismo<\/li>\n<\/ul>\n<p>Essas disciplinas foram cuidadosamente selecionadas para fornecer uma forma\u00e7\u00e3o abrangente e necess\u00e1ria para o exerc\u00edcio respons\u00e1vel da profiss\u00e3o.<\/p>\n<h2>Objetivo do curso para motoristas<\/h2>\n<p>O principal objetivo desta forma\u00e7\u00e3o \u00e9 preparar motoristas para desempenhar fun\u00e7\u00f5es com seguran\u00e7a e efici\u00eancia. Os participantes aprender\u00e3o a lidar com diferentes situa\u00e7\u00f5es que podem ocorrer durante a condu\u00e7\u00e3o de ve\u00edculos, al\u00e9m de conhecer as legisla\u00e7\u00f5es que regem o tr\u00e2nsito, contribuindo assim para uma mobilidade urbana mais segura e organizada.<\/p>\n<h2>Vantagens de se especializar como motorista<\/h2>\n<p>Investir em uma forma\u00e7\u00e3o espec\u00edfica traz diversas vantagens, especialmente em um mercado de trabalho competitivo. Algumas das principais vantagens incluem:<\/p>\n<ul>\n<li><strong>Qualidade no servi\u00e7o:<\/strong> Motoristas bem treinados oferecem um atendimento superior aos passageiros.<\/li>\n<li><strong>Reconhecimento profissional:<\/strong> Ter um curso de qualifica\u00e7\u00e3o torna o motorista mais vis\u00edvel no mercado, aumentando as oportunidades de emprego.<\/li>\n<li><strong>Atualiza\u00e7\u00e3o constante:<\/strong> O curso incentiva a atualiza\u00e7\u00e3o de conhecimentos e habilidades, essenciais em um setor em constante evolu\u00e7\u00e3o.<\/li>\n<li><strong>Seguran\u00e7a para todos:<\/strong> Profissionais bem preparados ajudam a tornar o tr\u00e2nsito mais seguro para todos os usu\u00e1rios.<\/li>\n<\/ul>\n<h2>Impacto da qualifica\u00e7\u00e3o no servi\u00e7o de transporte<\/h2>\n<p>A qualifica\u00e7\u00e3o profissional tem um impacto direto na qualidade do servi\u00e7o prestado. Quando os motoristas est\u00e3o bem treinados, a satisfa\u00e7\u00e3o do cliente aumenta, resultando em maior fideliza\u00e7\u00e3o e recomenda\u00e7\u00f5es. Al\u00e9m disso, a forma\u00e7\u00e3o adequada contribui para a redu\u00e7\u00e3o de acidentes, j\u00e1 que motoristas capacitados tendem a ser mais cautelosos e prudentes.<\/p>\n<h2>Como o curso se alinha aos ODS da ONU<\/h2>\n<p>O curso de forma\u00e7\u00e3o para motoristas profissionais tamb\u00e9m se conecta ao quarto Objetivo de Desenvolvimento Sustent\u00e1vel (ODS) da ONU, que visa garantir uma educa\u00e7\u00e3o de qualidade inclusiva e equitativa, promovendo oportunidades de aprendizado ao longo da vida. Ao oferecer esse treinamento, a Prefeitura de Santos n\u00e3o apenas promove o desenvolvimento profissional, mas tamb\u00e9m contribui para um futuro mais seguro e respons\u00e1vel no transporte urbano.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Inscri\u00e7\u00f5es para o Curso de Motorista Profissional em Santos v\u00e3o at\u00e9 o dia 12.<\/p>\n","protected":false},"author":1,"featured_media":5005,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-5006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-em-santos","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Curso para motorista profissional de Santos inscreve at\u00e9 o dia 12 - Encontra Santos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curso para motorista profissional de Santos inscreve at\u00e9 o dia 12 - Encontra Santos\" \/>\n<meta property=\"og:description\" content=\"Inscri\u00e7\u00f5es para o Curso de Motorista Profissional em Santos v\u00e3o at\u00e9 o dia 12.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontra Santos\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T15:56:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.encontrasantos.com.br\/sobre\/wp-content\/uploads\/2026\/02\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12.webp\" \/>\n<meta name=\"author\" content=\"Encontra Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Encontra Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\\\/\"},\"author\":{\"name\":\"Encontra Santos\",\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/c048a1af2d003b660d350a57d8081717\"},\"headline\":\"Curso para motorista profissional de Santos inscreve at\u00e9 o dia 12\",\"datePublished\":\"2026-02-03T15:56:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\\\/\"},\"wordCount\":699,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12.webp\",\"articleSection\":[\"Not\u00edcias Santos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\\\/\",\"url\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\\\/\",\"name\":\"Curso para motorista profissional de Santos inscreve at\u00e9 o dia 12 - Encontra Santos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12.webp\",\"datePublished\":\"2026-02-03T15:56:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/c048a1af2d003b660d350a57d8081717\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12.webp\",\"contentUrl\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12.webp\",\"width\":280,\"height\":280,\"caption\":\"curso para motorista profissional de Santos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curso para motorista profissional de Santos inscreve at\u00e9 o dia 12\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/\",\"name\":\"Encontra Santos\",\"description\":\"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Santos e regi\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/c048a1af2d003b660d350a57d8081717\",\"name\":\"Encontra Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"caption\":\"Encontra Santos\"},\"sameAs\":[\"http:\\\/\\\/www.encontrasantos.com.br\"],\"url\":\"https:\\\/\\\/www.encontrasantos.com.br\\\/sobre\\\/author\\\/esantos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curso para motorista profissional de Santos inscreve at\u00e9 o dia 12 - Encontra Santos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/","og_locale":"pt_BR","og_type":"article","og_title":"Curso para motorista profissional de Santos inscreve at\u00e9 o dia 12 - Encontra Santos","og_description":"Inscri\u00e7\u00f5es para o Curso de Motorista Profissional em Santos v\u00e3o at\u00e9 o dia 12.","og_url":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/","og_site_name":"Encontra Santos","article_published_time":"2026-02-03T15:56:08+00:00","og_image":[{"url":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-content\/uploads\/2026\/02\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12.webp","type":"","width":"","height":""}],"author":"Encontra Santos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Encontra Santos","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/#article","isPartOf":{"@id":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/"},"author":{"name":"Encontra Santos","@id":"https:\/\/www.encontrasantos.com.br\/sobre\/#\/schema\/person\/c048a1af2d003b660d350a57d8081717"},"headline":"Curso para motorista profissional de Santos inscreve at\u00e9 o dia 12","datePublished":"2026-02-03T15:56:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/"},"wordCount":699,"commentCount":0,"image":{"@id":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-content\/uploads\/2026\/02\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12.webp","articleSection":["Not\u00edcias Santos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/","url":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/","name":"Curso para motorista profissional de Santos inscreve at\u00e9 o dia 12 - Encontra Santos","isPartOf":{"@id":"https:\/\/www.encontrasantos.com.br\/sobre\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/#primaryimage"},"image":{"@id":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-content\/uploads\/2026\/02\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12.webp","datePublished":"2026-02-03T15:56:08+00:00","author":{"@id":"https:\/\/www.encontrasantos.com.br\/sobre\/#\/schema\/person\/c048a1af2d003b660d350a57d8081717"},"breadcrumb":{"@id":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/#primaryimage","url":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-content\/uploads\/2026\/02\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12.webp","contentUrl":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-content\/uploads\/2026\/02\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12.webp","width":280,"height":280,"caption":"curso para motorista profissional de Santos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontrasantos.com.br\/sobre\/curso-para-motorista-profissional-de-santos-inscreve-ate-o-dia-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontrasantos.com.br\/sobre\/"},{"@type":"ListItem","position":2,"name":"Curso para motorista profissional de Santos inscreve at\u00e9 o dia 12"}]},{"@type":"WebSite","@id":"https:\/\/www.encontrasantos.com.br\/sobre\/#website","url":"https:\/\/www.encontrasantos.com.br\/sobre\/","name":"Encontra Santos","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Santos e regi\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encontrasantos.com.br\/sobre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.encontrasantos.com.br\/sobre\/#\/schema\/person\/c048a1af2d003b660d350a57d8081717","name":"Encontra Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","caption":"Encontra Santos"},"sameAs":["http:\/\/www.encontrasantos.com.br"],"url":"https:\/\/www.encontrasantos.com.br\/sobre\/author\/esantos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/posts\/5006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=5006"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/posts\/5006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/media\/5005"}],"wp:attachment":[{"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=5006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=5006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrasantos.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=5006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}